{"id":1778,"count":1,"description":"","link":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/","name":"corante alimentar","slug":"corante-alimentar","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de corante alimentar - Blog Brastokio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de corante alimentar - Blog Brastokio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Brastokio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/\",\"url\":\"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/\",\"name\":\"Arquivo de corante alimentar - Blog Brastokio\",\"isPartOf\":{\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.brastokio.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"corante alimentar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/#website\",\"url\":\"https:\/\/www.brastokio.com.br\/blog\/\",\"name\":\"Blog Brastokio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brastokio.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/#organization\",\"name\":\"Blog Brastokio\",\"url\":\"https:\/\/www.brastokio.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.brastokio.com.br\/blog\/wp-content\/uploads\/2024\/09\/logo-1.png\",\"contentUrl\":\"https:\/\/www.brastokio.com.br\/blog\/wp-content\/uploads\/2024\/09\/logo-1.png\",\"width\":4500,\"height\":1082,\"caption\":\"Blog Brastokio\"},\"image\":{\"@id\":\"https:\/\/www.brastokio.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de corante alimentar - Blog Brastokio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de corante alimentar - Blog Brastokio","og_url":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/","og_site_name":"Blog Brastokio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/","url":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/","name":"Arquivo de corante alimentar - Blog Brastokio","isPartOf":{"@id":"https:\/\/www.brastokio.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.brastokio.com.br\/blog\/tag\/corante-alimentar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.brastokio.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"corante alimentar"}]},{"@type":"WebSite","@id":"https:\/\/www.brastokio.com.br\/blog\/#website","url":"https:\/\/www.brastokio.com.br\/blog\/","name":"Blog Brastokio","description":"","publisher":{"@id":"https:\/\/www.brastokio.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brastokio.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.brastokio.com.br\/blog\/#organization","name":"Blog Brastokio","url":"https:\/\/www.brastokio.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.brastokio.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.brastokio.com.br\/blog\/wp-content\/uploads\/2024\/09\/logo-1.png","contentUrl":"https:\/\/www.brastokio.com.br\/blog\/wp-content\/uploads\/2024\/09\/logo-1.png","width":4500,"height":1082,"caption":"Blog Brastokio"},"image":{"@id":"https:\/\/www.brastokio.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.brastokio.com.br\/blog\/wp-json\/wp\/v2\/tags\/1778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brastokio.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.brastokio.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.brastokio.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=1778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}